{"id":3207,"date":"2019-05-11T10:10:05","date_gmt":"2019-05-11T08:10:05","guid":{"rendered":"https:\/\/www.feuerwehr-liezen.at\/2018\/?p=3207"},"modified":"2019-05-14T08:15:34","modified_gmt":"2019-05-14T06:15:34","slug":"reifenpanne-fuehrte-zu-grossaufgebot-an-einsatzkraeften","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-liezen.at\/2018\/reifenpanne-fuehrte-zu-grossaufgebot-an-einsatzkraeften\/","title":{"rendered":"Reifenpanne f\u00fchrte zu Gro\u00dfaufgebot an Einsatzkr\u00e4ften"},"content":{"rendered":"\n<p>Am Samstag, 11. Mai um 10:10 Uhr wurden die Feuerwehren Liezen-Stadt und D\u00f6llach zu einem vermeintlich schweren Verkehrsunfall im D\u00f6llacher Ortsteil &#8222;Fuchsluken&#8220; alarmiert. Mit der Information &#8222;LKW gegen Carport, vermutlich eingeklemmte Person&#8220; wurden auch Kr\u00e4fte des Roten Kreuzes und der Polizei zum Einsatzort gerufen.<\/p>\n\n\n\n<p>Vor Ort eingetroffen konnte durch den Einsatzleiter der \u00f6rtlich zust\u00e4ndigen Feuerwehr D\u00f6llach rasch Entwarnung gegeben werden. Es handelte sich lediglich um einen VW-Bus mit einer Reifenpanne an der Vorderachse, welcher unter einem Carport zum Stillstand kam. Verletzt wurde dabei niemand.<\/p>\n\n\n\n<p>Die 17 Kameradinnen und Kameraden der FF Liezen-Stadt, welche mit drei Fahrzeugen anger\u00fcckt waren, konnten somit knapp nach einer Viertelstunde den Einsatz beenden und wieder in das R\u00fcsthaus einr\u00fccken<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Samstag, 11. Mai um 10:10 Uhr wurden die Feuerwehren Liezen-Stadt und D\u00f6llach zu einem vermeintlich schweren Verkehrsunfall im D\u00f6llacher Ortsteil &#8222;Fuchsluken&#8220; alarmiert. Mit der Information &#8222;LKW gegen Carport, vermutlich eingeklemmte Person&#8220; wurden auch Kr\u00e4fte des Roten Kreuzes und der Polizei zum Einsatzort gerufen. Vor Ort eingetroffen konnte durch den Einsatzleiter der \u00f6rtlich zust\u00e4ndigen Feuerwehr [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einsatz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/3207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/comments?post=3207"}],"version-history":[{"count":3,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/3207\/revisions"}],"predecessor-version":[{"id":3211,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/3207\/revisions\/3211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media\/3210"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media?parent=3207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/categories?post=3207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/tags?post=3207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}