{"id":3043,"date":"2019-04-02T14:34:29","date_gmt":"2019-04-02T12:34:29","guid":{"rendered":"https:\/\/www.feuerwehr-liezen.at\/2018\/?p=3043"},"modified":"2019-04-02T14:34:32","modified_gmt":"2019-04-02T12:34:32","slug":"brandmeldealarm-bei-der-fa-forstinger","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-liezen.at\/2018\/brandmeldealarm-bei-der-fa-forstinger\/","title":{"rendered":"Brandmeldealarm bei der Fa. Forstinger"},"content":{"rendered":"\n<p>Zu einem Brandmeldealarm bei der Fa. Forstinger wurde die FF Liezen-Stadt heute Mittag alarmiert. Kurz nach dem Eintreffen der Einsatzkr\u00e4fte konnte auch schon wieder Entwarnung gegeben werden, da es sich um einen Fehlalarm handelte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zu einem Brandmeldealarm bei der Fa. Forstinger wurde die FF Liezen-Stadt heute Mittag alarmiert. Kurz nach dem Eintreffen der Einsatzkr\u00e4fte konnte auch schon wieder Entwarnung gegeben werden, da es sich um einen Fehlalarm handelte.<\/p>\n","protected":false},"author":1,"featured_media":3018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einsatz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/3043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/comments?post=3043"}],"version-history":[{"count":2,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/3043\/revisions"}],"predecessor-version":[{"id":3045,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/3043\/revisions\/3045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media\/3018"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media?parent=3043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/categories?post=3043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/tags?post=3043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}