{"id":2674,"date":"2017-07-30T08:26:26","date_gmt":"2017-07-30T06:26:26","guid":{"rendered":"https:\/\/www.feuerwehr-liezen.at\/2018\/?p=2674"},"modified":"2019-01-25T08:28:08","modified_gmt":"2019-01-25T07:28:08","slug":"jugendferienaktion-wasser-marsch-brand-aus","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-liezen.at\/2018\/jugendferienaktion-wasser-marsch-brand-aus\/","title":{"rendered":"Jugendferienaktion: Wasser marsch &#038; Brand aus!"},"content":{"rendered":"\n<p><strong>Wasser marsch &amp; Brand aus!<\/strong><\/p>\n\n\n\n<p>Auch heuer hei\u00dft es wieder: &#8222;Einsatz bei der Feuerwehr Liezen&#8220;! Jetzt anmelden, wir haben noch freie Pl\u00e4tze!<\/p>\n\n\n\n<p>Einen Tag lang Feuerwehrmann sein: Ihr werdet einen Brand l\u00f6schen, mit der Drehleiter ausfahren, durch einen verrauchten Raum robben, mit einem Feuerl\u00f6scher hantieren und mit den verschiedenen Feuerwehrautos ausfahren. Die Feuerwehrleute der FF Liezen-Stadt zeigen euch was los ist, wenn der Ernstfall eintritt und ihr seid mittendrin. Ein ganz besonderes Erlebnis, welches ihr nicht verpassen solltet!<\/p>\n\n\n\n<p>Wir freuen uns auf alle M\u00e4dchen und Burschen zwischen 10 und 16 Jahren!<\/p>\n\n\n\n<p>Mitzubringen sind gute Schuhe und jede Menge guter Laune!<\/p>\n\n\n\n<p><strong>Wann?<\/strong>&nbsp;Samstag 05. August 2017<\/p>\n\n\n\n<p><strong>Uhrzeit?<\/strong>&nbsp;von 9:00 bis 16:00 Uhr<\/p>\n\n\n\n<p><strong>Treffpunkt?<\/strong>&nbsp;R\u00fcsthaus Feuerwehr Liezen-Stadt<\/p>\n\n\n\n<p>Anmeldung \u00fcber unseren Jugendwart OLM dF. Gunar Braunsberger<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Telefon: 0664\/6035 3425<\/li><li>E-Mail:&nbsp;<a href=\"mailto:gunar.braunsberger@liezen.at\">gunar.braunsberger(at)liezen.at<\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wasser marsch &amp; Brand aus! Auch heuer hei\u00dft es wieder: &#8222;Einsatz bei der Feuerwehr Liezen&#8220;! Jetzt anmelden, wir haben noch freie Pl\u00e4tze! Einen Tag lang Feuerwehrmann sein: Ihr werdet einen Brand l\u00f6schen, mit der Drehleiter ausfahren, durch einen verrauchten Raum robben, mit einem Feuerl\u00f6scher hantieren und mit den verschiedenen Feuerwehrautos ausfahren. Die Feuerwehrleute der FF [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[102],"tags":[],"class_list":["post-2674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jugend"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/2674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/comments?post=2674"}],"version-history":[{"count":1,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/2674\/revisions"}],"predecessor-version":[{"id":2676,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/2674\/revisions\/2676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media\/2675"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media?parent=2674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/categories?post=2674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/tags?post=2674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}