{"id":10751,"date":"2024-05-28T07:32:00","date_gmt":"2024-05-28T05:32:00","guid":{"rendered":"https:\/\/www.feuerwehr-liezen.at\/2018\/?p=10751"},"modified":"2024-05-28T11:32:00","modified_gmt":"2024-05-28T09:32:00","slug":"ladegutverlust-behindert-morgenverkehr-in-liezen","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-liezen.at\/2018\/ladegutverlust-behindert-morgenverkehr-in-liezen\/","title":{"rendered":"Ladegutverlust behindert Morgenverkehr in Liezen"},"content":{"rendered":"\n<p>Ein LKW hat Dienstagfr\u00fch in einem Kreisverkehr in Liezen-Ost hunderte Bierkisten verloren. Das Ladegut landete verstreut auf der Fahrbahn.<\/p>\n\n\n\n<p>Die Einsatzkr\u00e4fte der Feuerwehr Liezen-Stadt wurden gegen 7:30 Uhr zu Aufr\u00e4umarbeiten nach einem Ladegutverlust alarmiert. Im Kreisverkehr an der Kreuzung der B320 &#8211; Ennstalstra\u00dfe &#8211; mit der A9-Autobahnauffahrt sowie der B146 &#8211; Ges\u00e4use Stra\u00dfe und der Werkstra\u00dfe, im Stadtgebiet von Liezen, hat ein LKW einen Gro\u00dfteil seiner Ladung verloren. Die Bierkisten sowie unz\u00e4hlige Bierflaschen verteilten sich auf der Fahrbahn. Die Einsatzkr\u00e4fte zweier Feuerwehren waren mehrere Stunden damit besch\u00e4ftigt, die Flaschen und Kisten zu bergen, beziehungsweise die zerbrochenen Flaschen von der Fahrbahn zu beseitigen. Mit einer zahlreichen Unterst\u00fctzung der Stra\u00dfenmeisterei Liezen, einem Radlader und einem Kipp-Lkw sowie dem Stapler eines nahegelegenen Industriebetriebes wurden die zerbrochenen Bierflaschen verladen und in weiterer Folge entsorgt. Der Rest der Ladung musste gesichert werden, danach konnte das besch\u00e4digte Sattelkraftfahrzeug unter Begleitung der Polizei die Unfallstelle verlassen.<\/p>\n\n\n\n<p>Mittels einer Kehrmaschine wurde die Fahrbahn von den restlichen Glasscherben gereinigt, sodass der betroffene Knotenpunkt gegen 10 Uhr wieder f\u00fcr den Verkehr vollst\u00e4ndig freigegeben werden konnte. Aufgrund der beengten Verkehrsf\u00fchrung im Einsatzbereich (Kreisverkehr und Autobahnauffahrt) kam es im Morgenverkehr zu erheblichen Beeintr\u00e4chtigungen und R\u00fcckstaus.<\/p>\n\n\n\n<p><strong>Eingesetzt waren:<\/strong><br> &#8211;   Feuerwehr Liezen-Stadt mit 10 Kamerad:innen und 2 Fahrzeugen (TLF-A 4000, LKW-A)<br> &#8211;   Feuerwehr Pyhrn mit 10 Kamerad:innen und 2 Fahrzeugen (HLF 2, KLFA)<br> &#8211;   Stra\u00dfenmeisterei Liezen mit 9 Mitarbeiter:innen und Stra\u00dfenmeister<br> &#8211;   Polizei Liezen mit 2 Polizisten<br> &#8211;   Privatunternehmen mit Kehrmaschine<br> &#8211;   Privatunternehmen mit Stapler und Euro-Paletten<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-2-1-scaled.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"10760\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-2-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-10760\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-2-1-1024x768.jpeg 1024w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-2-1-300x225.jpeg 300w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-2-1-768x576.jpeg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-2-1-1536x1152.jpeg 1536w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-2-1-2048x1536.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-3-1-scaled.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"10759\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-3-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-10759\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-3-1-1024x768.jpeg 1024w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-3-1-300x225.jpeg 300w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-3-1-768x576.jpeg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-3-1-1536x1152.jpeg 1536w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-3-1-2048x1536.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-1-scaled.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"10761\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-10761\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-1-1024x768.jpeg 1024w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-1-300x225.jpeg 300w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-1-768x576.jpeg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-1-1536x1152.jpeg 1536w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-28-at-09.52.24-1-2048x1536.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ein LKW hat Dienstagfr\u00fch in einem Kreisverkehr in Liezen-Ost hunderte Bierkisten verloren. Das Ladegut landete verstreut auf der Fahrbahn. Die Einsatzkr\u00e4fte der Feuerwehr Liezen-Stadt wurden gegen 7:30 Uhr zu Aufr\u00e4umarbeiten nach einem Ladegutverlust alarmiert. Im Kreisverkehr an der Kreuzung der B320 &#8211; Ennstalstra\u00dfe &#8211; mit der A9-Autobahnauffahrt sowie der B146 &#8211; Ges\u00e4use Stra\u00dfe und der [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einsatz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/comments?post=10751"}],"version-history":[{"count":3,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10751\/revisions"}],"predecessor-version":[{"id":10762,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10751\/revisions\/10762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media\/10759"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media?parent=10751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/categories?post=10751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/tags?post=10751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}