{"id":10671,"date":"2024-04-10T17:32:00","date_gmt":"2024-04-10T15:32:00","guid":{"rendered":"https:\/\/www.feuerwehr-liezen.at\/2018\/?p=10671"},"modified":"2024-04-15T09:53:10","modified_gmt":"2024-04-15T07:53:10","slug":"binden-von-betriebsmitteln-in-der-werkstrasse","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-liezen.at\/2018\/binden-von-betriebsmitteln-in-der-werkstrasse\/","title":{"rendered":"Binden von Betriebsmitteln in der Werkstra\u00dfe"},"content":{"rendered":"\n<p>Aus bislang ungekl\u00e4rter Ursache verlor am Mittwoch, 10. April vermutlich ein Pkw im Kreuzungsbereich der Werkstra\u00dfe Betriebsmittel, welche es galt mittels eines speziellen Bindemittels zu entfernen. Die Feuerwehr Liezen-Stadt war in Folge dessen mit zwei Fahrzeugen und 10 Mann im Einsatz, ebenso wie die Polizei mit einem Fahrzeug und zwei Polizist:innen. Der Einsatz konnte nach etwas mehr als einer halben Stunde beendet werden.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1423.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"10672\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1423-1024x768.jpeg\" alt=\"\" class=\"wp-image-10672\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1423-1024x768.jpeg 1024w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1423-300x225.jpeg 300w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1423-768x576.jpeg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1423-1536x1152.jpeg 1536w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1423.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1424.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"10673\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1424-1024x768.jpeg\" alt=\"\" class=\"wp-image-10673\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1424-1024x768.jpeg 1024w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1424-300x225.jpeg 300w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1424-768x576.jpeg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1424-1536x1152.jpeg 1536w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/04\/IMG_1424.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Aus bislang ungekl\u00e4rter Ursache verlor am Mittwoch, 10. April vermutlich ein Pkw im Kreuzungsbereich der Werkstra\u00dfe Betriebsmittel, welche es galt mittels eines speziellen Bindemittels zu entfernen. Die Feuerwehr Liezen-Stadt war in Folge dessen mit zwei Fahrzeugen und 10 Mann im Einsatz, ebenso wie die Polizei mit einem Fahrzeug und zwei Polizist:innen. Der Einsatz konnte nach [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einsatz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/comments?post=10671"}],"version-history":[{"count":1,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10671\/revisions"}],"predecessor-version":[{"id":10674,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10671\/revisions\/10674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media\/10673"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media?parent=10671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/categories?post=10671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/tags?post=10671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}