{"id":10476,"date":"2024-03-02T07:51:52","date_gmt":"2024-03-02T06:51:52","guid":{"rendered":"https:\/\/www.feuerwehr-liezen.at\/2018\/?p=10476"},"modified":"2024-03-05T07:54:29","modified_gmt":"2024-03-05T06:54:29","slug":"blf-c-das-neue-fahrzeug-der-ff-liezen-stadt","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-liezen.at\/2018\/blf-c-das-neue-fahrzeug-der-ff-liezen-stadt\/","title":{"rendered":"BLF-C \u2013 Das neue Fahrzeug der FF Liezen-Stadt"},"content":{"rendered":"\n<p>Der Fuhrpark der Feuerwehr Liezen-Stadt umfasst aktuell 8 Fahrzeuge. Das \u00e4lteste Fahrzeug, ein 28 Jahre alter Land Rover (BLF \u2013 Berglandl\u00f6schfahrzeug) wurde im Jahr 2023 aus dem Fuhrpark ausgeschieden. Bereits 2022 wurde mit der Planung einer Ersatzbeschaffung f\u00fcr ein neues, gel\u00e4ndeg\u00e4ngiges Fahrzeug begonnen.&nbsp;<\/p>\n\n\n\n<p><strong><em>Flexibilit\u00e4t von gro\u00dfem Vorteil&nbsp;<\/em><\/strong><\/p>\n\n\n\n<p>Ein neues Fahrzeugkonzept ist das Quick-Change-Modul der Firma Kofler Fahrzeugbau in Lana (S\u00fcdtirol). Hierbei wird auf einem Tr\u00e4gerfahrzeug (Pickup) ein wechselbares Containersystem auf der Ladefl\u00e4che transportiert. Somit kann je nach Bedarf des Einsatzes, ein dementsprechend beladener Container am Einsatzfahrzeug mitgef\u00fchrt werden. Die taktische Bezeichnung dieses Fahrzeuges lautet BLF-C (Berge \u2013 L\u00f6schfahrzeug \u2013 Container).<\/p>\n\n\n\n<p>Die durch die Klimaerw\u00e4rmung f\u00fcr die Feuerwehren immer gr\u00f6\u00dfer werdenden Herausforderungen wie Waldbr\u00e4nde bzw. Unwetter machen dieses Fahrzeug mit seinem Konzept als sinnvolle Anschaffung aus.&nbsp;<\/p>\n\n\n\n<p>Zum einen wurde ein \u201eTechnik-Container\u201c beschafft, welcher neben einer Kettens\u00e4ge, Stromerzeuger, Beleuchtungsmittel, Werkzeug, Tauchpumpen etc. mitf\u00fchrt und bei Unwettern seinen Einsatz findet, so wurde zum anderen ein baugleicher \u201eBrand-Container\u201c beschafft, welcher durch eine Tragkraftspritze (PFPN 10-750) samt Schlauchmaterial zu L\u00f6scheins\u00e4tzen ausr\u00fccken kann.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/03\/Gruppenbild_blf-2-1024x683.jpg\" alt=\"\" class=\"wp-image-10478\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/03\/Gruppenbild_blf-2-1024x683.jpg 1024w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/03\/Gruppenbild_blf-2-300x200.jpg 300w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/03\/Gruppenbild_blf-2-768x512.jpg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/03\/Gruppenbild_blf-2-1536x1024.jpg 1536w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2024\/03\/Gruppenbild_blf-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Das neue Fahrzeug wurde am Samstag, den 2. M\u00e4rz 2024 offiziell von B\u00fcrgermeisterin Andrea Heinrich, 1. Vizeb\u00fcrgermeister Albert Krug und 2. Vizeb\u00fcrgermeister Egon Gojer an das Kommando der Feuerwehr Liezen-Stadt \u00fcbergeben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Fuhrpark der Feuerwehr Liezen-Stadt umfasst aktuell 8 Fahrzeuge. Das \u00e4lteste Fahrzeug, ein 28 Jahre alter Land Rover (BLF \u2013 Berglandl\u00f6schfahrzeug) wurde im Jahr 2023 aus dem Fuhrpark ausgeschieden. Bereits 2022 wurde mit der Planung einer Ersatzbeschaffung f\u00fcr ein neues, gel\u00e4ndeg\u00e4ngiges Fahrzeug begonnen.&nbsp; Flexibilit\u00e4t von gro\u00dfem Vorteil&nbsp; Ein neues Fahrzeugkonzept ist das Quick-Change-Modul der Firma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/comments?post=10476"}],"version-history":[{"count":1,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10476\/revisions"}],"predecessor-version":[{"id":10480,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10476\/revisions\/10480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media\/10479"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media?parent=10476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/categories?post=10476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/tags?post=10476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}