{"id":10248,"date":"2023-09-02T08:00:00","date_gmt":"2023-09-02T06:00:00","guid":{"rendered":"https:\/\/www.feuerwehr-liezen.at\/2018\/?p=10248"},"modified":"2023-09-05T11:40:22","modified_gmt":"2023-09-05T09:40:22","slug":"tagesausflug-der-feuerwehr-nach-riegersburg","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-liezen.at\/2018\/tagesausflug-der-feuerwehr-nach-riegersburg\/","title":{"rendered":"Tagesausflug der Feuerwehr nach Riegersburg"},"content":{"rendered":"\n<p>Zur mittlerweile liebgewordenen Tradition ist es geworden, im Zwei-Jahres-Rhythmus einen Tagesausflug der Feuerwehr abzuhalten. Vergangenen Samstag um 8 Uhr war es soweit: Der mit 31 Kamerad:innen der Feuerwehr Liezen-Stadt besetzte Bus startete die Reise nach Riegersburg, Bezirk S\u00fcdoststeiermark.<\/p>\n\n\n\n<p>Am Fu\u00dfe der Riegersburg angelangt war der erste Programmpunkt nicht mehr weit entfernt. Die bekannte <strong>Greifvogelshow <\/strong>galt als erstes Etappenziel. In etwas mehr als 45 Minuten gab es hier einige waghalsige Flugman\u00f6ver der verschiedenen Greifv\u00f6gel zu beobachten. Um sich nun aber f\u00fcr das weitere Tagesprogramm zu st\u00e4rken, wurde als kulinarischer Programmpunkt das <strong>Riegersburger Seehaus<\/strong> angesteuert.<\/p>\n\n\n\n<p>Um Kultur und Tradition dieser Gegend weiter kennenzulernen, war als n\u00e4chstes Zwischenziel die Erlebnistour der Firma <strong>G\u00f6lles <\/strong>gebucht. In der rund einst\u00fcndigen F\u00fchrung durch die Produktionsst\u00e4tte, wurde in \u00d6sterreichs gr\u00f6\u00dftem Essigfasskeller so mancher Geschmacksnerven tief auf die Wurzeln gef\u00fchlt. Eine Verkostung weniger ausgew\u00e4hlter, eigens produzierter Schn\u00e4pse aus dem Hause G\u00f6lles, umrahmte den Abschluss dieser Zwischenetappe.<\/p>\n\n\n\n<p>Bevor man aber noch den Bus zur Heimfahrt betrat, galt es im Weingut der <strong>Buschenschank Bernhart<\/strong>, bei k\u00f6stlicher &#8222;Brettljaus&#8217;n&#8220;, einzukehren. Hier konnten man noch knapp zwei gem\u00fctliche Stunden, im Kreise der Kameradschaft genie\u00dfen. Schlie\u00dflich trat man gegen 19 Uhr die Heimreise an.<\/p>\n\n\n\n<p>Um kurz nach 21 Uhr \u00f6ffneten sich die Bust\u00fcren in Liezen, auf einen spannenden und erlebnisreichen Tag kann zur\u00fcckgeblickt werden.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/1-gruppenfoto-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"10253\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/1-gruppenfoto-1024x768.jpg\" alt=\"\" class=\"wp-image-10253\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/1-gruppenfoto-1024x768.jpg 1024w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/1-gruppenfoto-300x225.jpg 300w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/1-gruppenfoto-768x576.jpg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/1-gruppenfoto-1536x1152.jpg 1536w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/1-gruppenfoto-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/2-greifvogel-scaled.jpg\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"10251\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/2-greifvogel-768x1024.jpg\" alt=\"\" class=\"wp-image-10251\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/2-greifvogel-768x1024.jpg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/2-greifvogel-225x300.jpg 225w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/2-greifvogel-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/3-goelles-scaled.jpg\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"10252\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/3-goelles-768x1024.jpg\" alt=\"\" class=\"wp-image-10252\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/3-goelles-768x1024.jpg 768w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/3-goelles-225x300.jpg 225w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/3-goelles-1152x1536.jpg 1152w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/3-goelles-1536x2048.jpg 1536w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/3-goelles-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/4-buschenschank-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" data-id=\"10250\" src=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/4-buschenschank-scaled.jpg\" alt=\"\" class=\"wp-image-10250\" srcset=\"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/4-buschenschank-scaled.jpg 1920w, https:\/\/www.feuerwehr-liezen.at\/2018\/wp-content\/uploads\/2023\/09\/4-buschenschank-225x300.jpg 225w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Zur mittlerweile liebgewordenen Tradition ist es geworden, im Zwei-Jahres-Rhythmus einen Tagesausflug der Feuerwehr abzuhalten. Vergangenen Samstag um 8 Uhr war es soweit: Der mit 31 Kamerad:innen der Feuerwehr Liezen-Stadt besetzte Bus startete die Reise nach Riegersburg, Bezirk S\u00fcdoststeiermark. Am Fu\u00dfe der Riegersburg angelangt war der erste Programmpunkt nicht mehr weit entfernt. Die bekannte Greifvogelshow galt [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einsatz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/comments?post=10248"}],"version-history":[{"count":2,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10248\/revisions"}],"predecessor-version":[{"id":10254,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/posts\/10248\/revisions\/10254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media\/10253"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/media?parent=10248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/categories?post=10248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-liezen.at\/2018\/wp-json\/wp\/v2\/tags?post=10248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}